{"id":1063,"date":"2018-04-27T00:00:00","date_gmt":"2018-04-26T22:00:00","guid":{"rendered":"https:\/\/great-kare.185-125-174-66.plesk.page\/die-junioren-zu-senioren-machen-erfolgreiche-nachfolge-faengt-frueh-an-2\/"},"modified":"2026-02-27T12:39:17","modified_gmt":"2026-02-27T11:39:17","slug":"die-junioren-zu-senioren-machen-erfolgreiche-nachfolge-faengt-frueh-an","status":"publish","type":"post","link":"https:\/\/www.kern-unternehmensnachfolge.com\/it\/die-junioren-zu-senioren-machen-erfolgreiche-nachfolge-faengt-frueh-an\/","title":{"rendered":"Die Junio\u00adren zu Senio\u00adren machen \u2013 erfolg\u00adrei\u00adcher Generations\u00adwechsel f\u00e4ngt fr\u00fch&nbsp;an"},"content":{"rendered":"<p><em>Fr\u00fch \u00fcbt sich, wer ein guter Unter\u00adneh\u00adme\u00adrIn sein will \u2013 Die \u201eSenio\u00adren\u201c sollten schon fr\u00fchzei\u00adtig die \u00dcberga\u00adbe des Lebens\u00adwerkes planen.<\/em><\/p>\n<p><em>M\u00f6chten Sie Ihre Kinder auf die Unternehmens\u00adnachfolge vorbereiten?<\/em><\/p>\n<h2>Sechs Schrit\u00adte zur erfolg\u00adrei\u00adchen Unternehmens\u00adnachfolge in der Familie:<\/h2>\n<p>Wie mache ich aus meinen Junio\u00adren erfolg\u00adrei\u00adche Senio\u00adren, damit mein Lebens\u00adwerk erfolg\u00adreich \u00fcbertra\u00adgen werden kann?<\/p>\n<h3>1.Einblick in das Familienunternehmen:<\/h3>\n<p>Sie sollten schon fr\u00fch daf\u00fcr sorgen, dass Ihre Kinder gelegent\u00adlich Einbli\u00adcke bekom\u00admen. Das kann man eigent\u00adlich ganz ungezwun\u00adgen errei\u00adchen , indem man die Kinder ab und zu mit in das Unter\u00adneh\u00admen nimmt, ihnen die verschie\u00adde\u00adnen Unter\u00adneh\u00admens\u00adbe\u00adrei\u00adche zeigt und sie einfach \u201eerkun\u00adden&nbsp;l\u00e4sst\u201c.<\/p>\n<p>Sp\u00e4ter dann, wenn sie gr\u00f6\u00dfer sind, bietet sich die M\u00f6glich\u00adkeit den Kindern durch Ferien\u00adjobs das Unter\u00adneh\u00admen n\u00e4her zu bringen. So beginnt eine gute Vorbe\u00adrei\u00adtung auf dem Weg die Junio\u00adren zu Senio\u00adren zu machen.<\/p>\n<h3>2.Erstklassige Ausbil\u00addung gew\u00e4hren:<\/h3>\n<p>Am besten nat\u00fcr\u00adlich mit einem Studi\u00aden\u00adschwer\u00adpunkt der sich auch im Unter\u00adneh\u00admens\u00adzweck wider\u00adspie\u00adgelt. Sinnvoll kann hier durch\u00adaus ein Studi\u00adum an einer sehr praxis\u00adori\u00aden\u00adtier\u00adten priva\u00adten Hochschu\u00adle mit Auslands\u00adexper\u00adti\u00adse&nbsp;sein.<\/p>\n<h3>3.\u201cDie Kinder vom Hof&nbsp;jagen\u201c:<\/h3>\n<p>D.h. ihnen die M\u00f6glich\u00adkeit nach dem Studi\u00adum zu geben, sich frei zu entfal\u00adten, selbst zu entschei\u00adden f\u00fcr wen sie wo arbei\u00adten m\u00f6chten. Am sch\u00f6ns\u00adten ist es nat\u00fcr\u00adlich, wenn sie zu direk\u00adten Mitbe\u00adwer\u00adbern gehen k\u00f6nnen. Das wird aber eher selten gelin\u00adgen. Aber vielleicht gibt es Kolle\u00adgen, Liefe\u00adran\u00adten oder auch Kunden, bei denen man viel Wissen f\u00fcr den eigenen Betrieb aufneh\u00admen&nbsp;kann.<\/p>\n<h3>4.\u201cDen eigenen Betrieb sexy machen\u201c:<\/h3>\n<p>Bef\u00fcrch\u00adten Sie, dass Ihre Kinder nach einem Studi\u00adum und den ersten Schrit\u00adten auf fremdem Terrain verw\u00f6hnt werden von den Verlo\u00adckun\u00adgen der gro\u00dfen weiten Welt. Dann sorgen Sie recht\u00adzei\u00adtig daf\u00fcr, dass Ihr Unter\u00adneh\u00admen eine Perspek\u00adti\u00adve bietet, die so inter\u00ades\u00adsant ist, dass Ihre Kinder gerne zur\u00fcck\u00adkom\u00admen wollen.<\/p>\n<p>Ihr Nachwuchs tritt mit einem ganz anderen Selbst\u00adbe\u00adwusst\u00adsein auf, wenn er in fremden Betrie\u00adben F\u00fchrungs\u00ader\u00adfah\u00adrung sammeln konnte. Auch die Akzep\u00adtanz ihrer Mitar\u00adbei\u00adter d\u00fcrfte deutlich h\u00f6her sein, wenn alle wissen, wo, mit welcher Verant\u00adwor\u00adtung Ihre Kinder bereits t\u00e4tig gewesen sind. Sonst hei\u00dft es schnell \u201cTheorie und Praxis \u2013 zwei Welten prallen aufein\u00adan\u00adder\u201c. Immer dann, wenn Sie Ihre Kinder direkt von der Univer\u00adsi\u00adt\u00e4t ins eigene Unter\u00adneh\u00admen&nbsp;holen.<\/p>\n<h3>5.Den \u00dcbergang gleitend gestalten:<\/h3>\n<p>\u00dcberle\u00adgen Sie sich konkre\u00adte Verant\u00adwor\u00adtungs\u00adbe\u00adrei\u00adche, die Sie Ihren Kindern anver\u00adtrau\u00aden wollen, ohne wirklich hinein\u00adzu\u00adre\u00adden und im Tages\u00adge\u00adsch\u00e4ft mitzumischen.<\/p>\n<p>Lassen Sie Fehler zu, aber nicht zweimal den gleichen und wenn es nicht all zu teuer&nbsp;wird.<\/p>\n<p>Diszi\u00adpli\u00adnie\u00adren sie sich selbst, indem Sie mit Ihren Kindern gemein\u00adsam feste Kommu\u00adni\u00adka\u00adti\u00adons\u00adstruk\u00adtu\u00adren und verbind\u00adli\u00adcher Arbeits\u00adab\u00adl\u00e4u\u00adfe verein\u00adba\u00adren. Auch wenn es schwer f\u00e4llt, halten Sie sich selber daran, damit es nicht direkt zu Streit kommt.<\/p>\n<p>\u00dcberge\u00adben sie sukzes\u00adsi\u00adve mehr Verant\u00adwor\u00adtung. Lassen Sie los und verl\u00e4n\u00adgern Sie die Leine. Ihren Kindern sollte man raten auch zu fordern.<\/p>\n<p>Bevor sie Ihren Kindern planen etwas zu verer\u00adben, g\u00f6nnen Sie Ihnen lieber die beste Ausbil\u00addung. Es muss nicht immer eine Privat\u00aduni\u00adver\u00adsi\u00adt\u00e4t sein, auch gute \u00f6ffent\u00adli\u00adche Hochschu\u00adlen eignen sich f\u00fcr die Fortbil\u00addung der Junio\u00adren. Aller\u00addings sollte man grund\u00ads\u00e4tz\u00adlich einen Auslands\u00adauf\u00adent\u00adhalt einpla\u00adnen, auch wenn das f\u00fcr das eigene Unter\u00adneh\u00admen aktuell keine beson\u00adde\u00adre Relevanz hat. Die Welt \u00e4ndert sich, und das schnel\u00adler als wir denken. Zudem pr\u00e4gt ein Auslands\u00adauf\u00adent\u00adhalt, sch\u00e4rft die Wahrneh\u00admung, festigt das Selbst\u00adbe\u00adwusst\u00adsein und f\u00f6rdert die Sprachkenntnisse.<\/p>\n<h3>6.Eine klare Road-Map formu\u00adlie\u00adren und verbind\u00adlich einhalten:<\/h3>\n<p>Verein\u00adba\u00adren Sie mit Ihren Junio\u00adren, wann sie konkret welche Verant\u00adwor\u00adtung erhal\u00adten. Zum Beispiel, welche Unter\u00adneh\u00admens\u00adbe\u00adrei\u00adche, Vollmach\u00adten oder Prokura.<\/p>\n<p>Legen Sie fest, wann die Junio\u00adren in Ihre Fu\u00dfstap\u00adfen treten.<\/p>\n<p>Gr\u00fcnden Sie gegebe\u00adnen\u00adfalls einen Beirat mit fremdem Vorsit\u00adzen\u00adden. Das entkrampft den Umgang mitein\u00adan\u00adder und f\u00fchrt schnel\u00adler zum gew\u00fcnsch\u00adten Erfolg.<\/p>\n<h4>Tipps zum Weiterlesen:<\/h4>\n<p><a class=\"yoast-link-suggestion__value\" href=\"https:\/\/www.kern-unternehmensnachfolge.com\/it\/innerfamiliaere-unternehmensnachfolge\/\" target=\"_blank\" rel=\"noopener noreferrer\">Inter\u00adview: Die inner\u00adfa\u00admi\u00adli\u00e4\u00adre Unternehmens\u00adnachfolge gut vorbereiten<\/a><\/p>\n<p><a href=\"https:\/\/www.kern-unternehmensnachfolge.com\/it\/5-tipps-fuer-eine-erfolgreiche-unternehmensnachfolge-2\/\">5 Tipps zur erfolg\u00adrei\u00adchen Unternehmensnachfolge<\/a><\/p>\n<p><a href=\"https:\/\/www.kern-unternehmensnachfolge.com\/it\/webinare\/\">Gratis Webinar zur Unternehmensnachfolge<\/a><\/p>\n<p><a href=\"https:\/\/www.kern-unternehmensnachfolge.com\/it\/mitarbeiterinformation-beim-unternehmensverkauf-wann-ist-der-richtige-zeitpunkt-2\/\">Mitar\u00adbei\u00adter\u00adin\u00adfor\u00adma\u00adti\u00adon beim Unternehmensverkauf<\/a><\/p>\n<p><a href=\"https:\/\/www.kern-unternehmensnachfolge.com\/it\/der-beirat-im-familienunternehmen-sinnvolles-instrument-der-unternehmensnachfolge-2\/\">Der Beirat in Familienunternehmen<\/a><\/p>\n<p><a href=\"https:\/\/www.kern-unternehmensnachfolge.com\/it\/verhandeln-auf-augenhoehe-auch-mit-konzernen-ist-das-moeglich-2\/\">Verhan\u00addeln auf Augen\u00adh\u00f6\u00adhe \u2013 auch mit Konzernen<\/a><\/p>\n\n\n<hr class=\"wp-block-separator is-style-wide\">\n\n\n<div id=\"rank-math-faq\" class=\"rank-math-block\">\n<div class=\"rank-math-list\">\n<div id=\"faq-question-69a1826531188\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question\">Wie kann ich meinen Kindern das Famili\u00aden\u00adun\u00adter\u00adneh\u00admen n\u00e4her bringen?<\/h3>\n<div class=\"rank-math-answer\">\n\n<p>Schon fr\u00fch kann man ihnen die verschie\u00adde\u00adnen Berei\u00adche zeigen und sie erkun\u00adden lassen. Sp\u00e4ter bieten sich Ferien\u00adjobs als Vorbe\u00adrei\u00adtung zum erfolg\u00adrei\u00adchen Generations\u00adwechsel an.&nbsp;<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-69a182653118b\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question\">Wie kann ich einen Generations\u00adwechsel mit meinen Kindern am besten vorbereiten?<\/h3>\n<div class=\"rank-math-answer\">\n\n<p>Bei der direk\u00adten Konkur\u00adrenz k\u00f6nnen die Junio\u00adren am meisten lernen. Aber auch bei Liefe\u00adran\u00adten oder Kunden k\u00f6nnen sie ihr Wissen erweitern.&nbsp;<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-69a182653118c\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question\">Wie kann ich beim Generations\u00adwechsel meinen Kindern den Einstieg in mein Unter\u00adneh\u00admen erleichtern?<\/h3>\n<div class=\"rank-math-answer\">\n\n<p>Definie\u00adren Sie Verant\u00adwor\u00adtungs\u00adbe\u00adrei\u00adche, in denen ihre Kinder eigen\u00adst\u00e4n\u00addig sind. Schaf\u00adfen Sie zudem  gemein\u00adsam feste Kommu\u00adni\u00adka\u00adti\u00adons\u00adstruk\u00adtu\u00adren und verbind\u00adli\u00adche Arbeits\u00adab\u00adl\u00e4u\u00adfe. Dann k\u00f6nnen sie immer mehr Verant\u00adwor\u00adtung an den Nachwuchs abgeben.&nbsp;<\/p>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Fr\u00fch \u00fcbt sich, wer ein guter UnternehmerIn sein will &#8211; Die &#8222;Senioren&#8220; sollten schon fr\u00fchzeitig die \u00dcbergabe des Lebenswerkes planen. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1064,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wp_typography_post_enhancements_disabled":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"iawp_total_views":0,"footnotes":"","tve_updated_post":"","tve_custom_css":"","tve_user_custom_css":"","tve_globals":{},"tcb2_ready":0,"tcb_editor_enabled":0,"tve_landing_page":"","_tve_header":"","_tve_footer":""},"categories":[7],"tags":[3953,206,195,197,217,218,626,202,627,494,243],"class_list":["post-1063","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-generationswechsel","tag-cta-webinar-generationswechsel","tag-familienbetrieb","tag-familienunternehmen","tag-generationswechsel","tag-generationswechsel-in-der-familie","tag-innerfamiliaerer-generationswechsel","tag-lebenswerk-uebergeben","tag-mittelstand","tag-nachwuchs-foerdern","tag-ruhrgebiet","tag-steuerliche-gestaltung"],"taxonomy_info":{"category":[{"value":7,"label":"Generationswechsel"}],"post_tag":[{"value":3953,"label":"CTA: Webinar Generationswechsel"},{"value":206,"label":"Familienbetrieb"},{"value":195,"label":"Familienunternehmen"},{"value":197,"label":"Generationswechsel"},{"value":217,"label":"Generationswechsel in der Familie"},{"value":218,"label":"innerfamili\u00e4rer Generationswechsel"},{"value":626,"label":"Lebenswerk \u00fcbergeben"},{"value":202,"label":"Mittelstand"},{"value":627,"label":"Nachwuchs f\u00f6rdern"},{"value":494,"label":"Ruhrgebiet"},{"value":243,"label":"Steuerliche Gestaltung"}]},"featured_image_src_large":["https:\/\/www.kern-unternehmensnachfolge.com\/wp-content\/uploads\/2018\/06\/silhouette-1082129_1280-1-1024x576.jpg",1024,576,true],"author_info":{"display_name":"Klaus Christian Knuffmann","author_link":"https:\/\/www.kern-unternehmensnachfolge.com\/it\/author\/klaus-christian-knuffmann\/"},"comment_info":0,"category_info":[{"term_id":7,"name":"Generationswechsel","slug":"generationswechsel","term_group":0,"term_taxonomy_id":7,"taxonomy":"category","description":"","parent":0,"count":20,"filter":"raw","cat_ID":7,"category_count":20,"category_description":"","cat_name":"Generationswechsel","category_nicename":"generationswechsel","category_parent":0}],"tag_info":[{"term_id":3953,"name":"CTA: Webinar Generationswechsel","slug":"cta-webinar-generationswechsel","term_group":0,"term_taxonomy_id":3953,"taxonomy":"post_tag","description":"","parent":0,"count":36,"filter":"raw"},{"term_id":206,"name":"Familienbetrieb","slug":"familienbetrieb","term_group":0,"term_taxonomy_id":206,"taxonomy":"post_tag","description":"","parent":0,"count":67,"filter":"raw"},{"term_id":195,"name":"Familienunternehmen","slug":"familienunternehmen","term_group":0,"term_taxonomy_id":195,"taxonomy":"post_tag","description":"","parent":0,"count":103,"filter":"raw"},{"term_id":197,"name":"Generationswechsel","slug":"generationswechsel","term_group":0,"term_taxonomy_id":197,"taxonomy":"post_tag","description":"","parent":0,"count":128,"filter":"raw"},{"term_id":217,"name":"Generationswechsel in der Familie","slug":"generationswechsel-in-der-familie","term_group":0,"term_taxonomy_id":217,"taxonomy":"post_tag","description":"","parent":0,"count":55,"filter":"raw"},{"term_id":218,"name":"innerfamili\u00e4rer Generationswechsel","slug":"innerfamiliaerer-generationswechsel","term_group":0,"term_taxonomy_id":218,"taxonomy":"post_tag","description":"","parent":0,"count":48,"filter":"raw"},{"term_id":626,"name":"Lebenswerk \u00fcbergeben","slug":"lebenswerk-uebergeben","term_group":0,"term_taxonomy_id":626,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw"},{"term_id":202,"name":"Mittelstand","slug":"mittelstand","term_group":0,"term_taxonomy_id":202,"taxonomy":"post_tag","description":"","parent":0,"count":71,"filter":"raw"},{"term_id":627,"name":"Nachwuchs f\u00f6rdern","slug":"nachwuchs-foerdern","term_group":0,"term_taxonomy_id":627,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw"},{"term_id":494,"name":"Ruhrgebiet","slug":"ruhrgebiet","term_group":0,"term_taxonomy_id":494,"taxonomy":"post_tag","description":"","parent":0,"count":10,"filter":"raw"},{"term_id":243,"name":"Steuerliche Gestaltung","slug":"steuerliche-gestaltung","term_group":0,"term_taxonomy_id":243,"taxonomy":"post_tag","description":"","parent":0,"count":18,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/www.kern-unternehmensnachfolge.com\/it\/wp-json\/wp\/v2\/posts\/1063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kern-unternehmensnachfolge.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kern-unternehmensnachfolge.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kern-unternehmensnachfolge.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kern-unternehmensnachfolge.com\/it\/wp-json\/wp\/v2\/comments?post=1063"}],"version-history":[{"count":0,"href":"https:\/\/www.kern-unternehmensnachfolge.com\/it\/wp-json\/wp\/v2\/posts\/1063\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kern-unternehmensnachfolge.com\/it\/wp-json\/wp\/v2\/media\/1064"}],"wp:attachment":[{"href":"https:\/\/www.kern-unternehmensnachfolge.com\/it\/wp-json\/wp\/v2\/media?parent=1063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kern-unternehmensnachfolge.com\/it\/wp-json\/wp\/v2\/categories?post=1063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kern-unternehmensnachfolge.com\/it\/wp-json\/wp\/v2\/tags?post=1063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}